{"id":16184,"date":"2021-12-10T10:35:01","date_gmt":"2021-12-10T13:35:01","guid":{"rendered":"https:\/\/realpax.com.br\/realpax\/?p=16184"},"modified":"2022-02-25T11:40:16","modified_gmt":"2022-02-25T14:40:16","slug":"checklist-para-o-final-de-ano-o-que-voce-ainda-pode-fazer-em-2021","status":"publish","type":"post","link":"https:\/\/realpax.com.br\/realpax\/checklist-para-o-final-de-ano-o-que-voce-ainda-pode-fazer-em-2021\/","title":{"rendered":"Voc\u00ea sabia? &#8211; Checklist para o final de ano! O que voc\u00ea ainda pode fazer em 2021"},"content":{"rendered":"<p dir=\"auto\">O ano est\u00e1 acabando, mas ainda d\u00e1 tempo de cumprir algumas das promessas que voc\u00ea fez no final do ano passado e ainda n\u00e3o conseguiu executar. Esse foi um ano bastante conturbado, n\u00e3o foi como n\u00f3s esper\u00e1vamos, mas ainda d\u00e1 tempo de come\u00e7ar uma boa mudan\u00e7a em 2021.<\/p>\n<p dir=\"auto\"><strong>Estamos prestes de nos despedirmos de 2020. Confira algumas coisas que voc\u00ea ainda pode fazer:<\/strong><\/p>\n<p dir=\"auto\">1- Passe mais tempo com sua fam\u00edlia<\/p>\n<p dir=\"auto\">Fam\u00edlia \u00e9 o nosso alicerce, e nestes dois \u00faltimos anos vimos como \u00e9 importante estar perto de quem n\u00f3s amamos. Fa\u00e7a atividades divertidas com seus filhos como: ver filmes, fazer uma noite de jogos ou uma tarde de lanches. Voc\u00ea tamb\u00e9m pode aproveitar e passar mais tempo com os seus pais.<\/p>\n<p dir=\"auto\">2- Arrume os seus arm\u00e1rios.<\/p>\n<p dir=\"auto\">Doe tudo o que n\u00e3o precisar mais, incentive seus filhos a darem aqueles brinquedos que est\u00e3o largados no canto. Voc\u00ea prestar\u00e1 um ato de solidariedade, ensinar\u00e1 uma \u00f3tima li\u00e7\u00e3o para as crian\u00e7as e deixar\u00e1 o seu arm\u00e1rio com uma cara nova.<\/p>\n<p dir=\"auto\">3- Sabe aquele livro esquecido na estante?<\/p>\n<p dir=\"auto\">\u00c9 uma \u00f3tima oportunidade para come\u00e7ar a ler. Os afazeres da nossa vida nos impedem de fazer o que gostamos. Aproveite o final do ano para por a sua leitura em dia.<\/p>\n<p dir=\"auto\">4 &#8211; Volte a falar com aquela pessoa que voc\u00ea n\u00e3o v\u00ea h\u00e1 anos.<\/p>\n<p dir=\"auto\">Hoje em dia, nos temos as redes sociais e o whatsapp para voltarmos a falar com os nossos amigos de escola ou aquele super companheiro de inf\u00e2ncia que as circunst\u00e2ncias ou a pr\u00f3pria vida afastou.<\/p>\n<p dir=\"auto\">5- Comece a fazer um curso<\/p>\n<p dir=\"auto\">Ainda d\u00e1 tempo de come\u00e7ar aprender um novo idioma, fazer aquele curso de capacita\u00e7\u00e3o que voc\u00ea estava deixando para depois.<\/p>\n<p dir=\"auto\">Voc\u00ea tamb\u00e9m pode come\u00e7ar a fazer metas para o pr\u00f3ximo ano, mas elas precisam ser realistas. N\u00e3o prometa o que voc\u00ea n\u00e3o conseguir\u00e1 cumprir. Estipule tarefas a curto prazo e n\u00e3o se esque\u00e7a: tenha foco. Voc\u00ea consegue!<\/p>\n<p dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15948 size-large\" src=\"https:\/\/i0.wp.com\/realpax.com.br\/realpax\/wp-content\/uploads\/2021\/04\/card-da-Ana-01-1024x144.jpg?resize=1024%2C144&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"144\" data-recalc-dims=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ano est\u00e1 acabando, mas ainda d\u00e1 tempo de cumprir algumas das promessas que voc\u00ea fez no final do ano passado e ainda n\u00e3o conseguiu executar. Esse foi um ano bastante conturbado, n\u00e3o foi como n\u00f3s esper\u00e1vamos, mas ainda d\u00e1 tempo de come\u00e7ar uma boa mudan\u00e7a em 2021. Estamos prestes de nos despedirmos de 2020. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16185,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/realpax.com.br\/realpax\/wp-content\/uploads\/2021\/12\/checklist_Prancheta-1.jpg?fit=998%2C562&ssl=1","_links":{"self":[{"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/posts\/16184"}],"collection":[{"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/comments?post=16184"}],"version-history":[{"count":3,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/posts\/16184\/revisions"}],"predecessor-version":[{"id":16246,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/posts\/16184\/revisions\/16246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/media\/16185"}],"wp:attachment":[{"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/media?parent=16184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/categories?post=16184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realpax.com.br\/realpax\/wp-json\/wp\/v2\/tags?post=16184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}